{"id":17833,"date":"2024-02-21T12:23:54","date_gmt":"2024-02-21T11:23:54","guid":{"rendered":"https:\/\/www.aeffelab.com\/?post_type=portfolio_page&#038;p=17833"},"modified":"2024-02-26T11:07:37","modified_gmt":"2024-02-26T10:07:37","slug":"leaeflo","status":"publish","type":"portfolio_page","link":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/","title":{"rendered":"Lea &#038; Fl\u00f2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17833\" class=\"elementor elementor-17833\" data-elementor-post-type=\"portfolio_page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7309c300 e-con-full e-flex e-con e-parent\" data-id=\"7309c300\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5fc20e2 e-con-full e-flex e-con e-parent\" data-id=\"5fc20e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21221a68 e-con-full e-flex e-con e-parent\" data-id=\"21221a68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e3584d5 elementor-widget elementor-widget-image\" data-id=\"2e3584d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leaeflo.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"144\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/logo-lef.svg\" class=\"attachment-full size-full wp-image-17844\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b53a057 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7b53a057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B2C<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ellipsis-v\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Replatforming<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f16417c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5f16417c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/leaeflo.com\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">visita il sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc853df elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"5cc853df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-df2d423\" href=\"https:\/\/www.facebook.com\/leaeflo\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d1d6773\" href=\"https:\/\/www.instagram.com\/leaeflo_official\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4afc79bf e-flex e-con-boxed e-con e-parent\" data-id=\"4afc79bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c4c18b9 elementor-widget elementor-widget-heading\" data-id=\"4c4c18b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Lea &amp; Fl\u00f2<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4711b74b elementor-widget elementor-widget-spacer\" data-id=\"4711b74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-650a4ecb elementor-widget elementor-widget-text-editor\" data-id=\"650a4ecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lea &amp; Fl\u00f2: punto di riferimento nella moda in fatto di eccellenza, entusiasmo e cortesia. La storia dell&#8217;azienda inizia nel 1989 quando i fratelli Alessandro e Remo Innocenti e le loro rispettive mogli Lea e Floriana aprono a Pescara il primo negozio di abbigliamento. Nel 2013 nasce Lea &amp; Fl\u00f2 Palace, un ampio concept store dove \u00e8 possibile trovare le ultime collezioni dei migliori brand fashion, un\u2019area relax con lounge bar e book store, un servizio di personal shopping. Dal 2017, il sito e-commerce leaeflo.com completa l&#8217;offerta, raggiungendo tutto il mondo con il suo stile e con promozioni vantaggiose. Oggi Lea &amp; Fl\u00f2 vanta oltre 30.000 clienti fidelizzati, pi\u00f9 di 70 collaboratori, diversi punti vendita tra negozi, outlet e monomarca.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40427883 e-con-full e-flex e-con e-parent\" data-id=\"40427883\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7ef18961 e-con-full e-flex e-con e-parent\" data-id=\"7ef18961\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-189a38d6 elementor-widget elementor-widget-heading\" data-id=\"189a38d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">e-commerce b2c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764d6613 elementor-widget elementor-widget-spacer\" data-id=\"764d6613\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c00b366 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2c00b366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span>Per Lea &amp; Fl\u00f2, AEFFE Lab ha sviluppato un sito su misura per le esigenze del brand e le sue caratteristiche uniche, puntando su velocit\u00e0, scalabilit\u00e0 e usabilit\u00e0. Nella home page, le immagini d\u2019impatto dello slider si alternano a nuovi arrivi e best seller, con uno stile pulito ed elegante. La forte brand identity \u00e8 stata ricreata digitalmente ed esaltata dai dettagli, in ottima mobile first: l\u2019utilizzo del colore arancione nell\u2019over sui testi e nei badge legati alla scontistica, gli elementi di navigazione, un menu che permette di navigare con semplicit\u00e0 tra tutte le principali categorie. Ogni scheda prodotto mostra in preview la disponibilit\u00e0 di colore e taglia, cos\u00ec da rendere la user experience veloce e orientata alla vendita. Le pagine prodotto danno ampio spazio a fotografie, descrizioni e dettagli, lasciando sempre in evidenza i pulsanti d\u2019azione dello shop. Rassicurato da recensioni positive, l&#8217;utente ha la possibilit\u00e0 di acquistare sia creando un proprio account che attraverso la social login e pu\u00f2 completare l\u2019acquisto attraverso una customer journey chiara e intuitiva.\u00a0<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-146fae00 e-con-full e-flex e-con e-parent\" data-id=\"146fae00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a55a2d6 elementor-widget elementor-widget-video\" data-id=\"a55a2d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/leaeflo-aeffelab-portfolio-ecommerce-b2c.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\" poster=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/leaeflo-aeffelab-portfolio-ecommerce-b2c.jpg\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-420e85bf e-con-full e-flex e-con e-parent\" data-id=\"420e85bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-14f018ad e-con-full e-flex e-con e-parent\" data-id=\"14f018ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfe60b8 elementor-widget elementor-widget-image\" data-id=\"dfe60b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/leaeflo-aeffelab-portfolio-replatforming-prestashop-bigcommerce.png\" class=\"attachment-full size-full wp-image-17856\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e07254 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-video\" data-id=\"9e07254\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-gimos-catalogo-scheda-prodotto.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ae23246 e-con-full e-flex e-con e-parent\" data-id=\"5ae23246\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69b410a4 elementor-widget elementor-widget-heading\" data-id=\"69b410a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">replatforming da Prestashop a BigCommerce<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b4638a6 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"6b4638a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71951af9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"71951af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span>AEFFE Lab ha soddisfatto la necessit\u00e0 di scalabilit\u00e0 di Lea &amp; Fl\u00f2, garantendo che l&#8217;e-commerce possa gestire picchi di traffico e attivit\u00e0 di acquisto senza compromettere le prestazioni o causare interruzioni. Come affrontare questa sfida che pu\u00f2 ostacolare il raggiungimento di obiettivi di crescita aziendale? Attraverso la decisione di migrare alla piattaforma BigCommerce, una soluzione Open SaaS in grado di integrare costi di manutenzione, hosting e conformit\u00e0 PCI, con un alto tasso di personalizzazione e offrendo un\u2019esperienza del marchio online fluida e coerente. Solitamente, scalare un e-commerce richiede un aumento della portata del server e modifiche alla struttura del sito. Con BigCommerce, questo non \u00e8 pi\u00f9 un problema poich\u00e9 la scalabilit\u00e0 \u00e8 automatica e si adatta dinamicamente all&#8217;afflusso di utenti e alla crescita dell\u2019attivit\u00e0, con prestazioni e sicurezza di alto livello.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff377e elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"6ff377e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9908e35 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"9908e35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.aeffelab.com\/it\/aeffelab-replatforming-bigcommerce\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">scarica la guida al replatforming<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71d02f56 e-con-full e-flex e-con e-parent\" data-id=\"71d02f56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3c58341c e-con-full e-flex e-con e-parent\" data-id=\"3c58341c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-589d9ed2 elementor-widget elementor-widget-heading\" data-id=\"589d9ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'\u2019app di AEFFE Lab per BigCommerce<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f48dea7 elementor-widget elementor-widget-image\" data-id=\"f48dea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/PM-store-banner.jpg\" class=\"attachment-full size-full wp-image-17863\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cde5e8d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1cde5e8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span>AEFFE Lab ha progettato e sviluppato \u201cProducts Management\u201d, un&#8217;app\/integrazione disponibile nel marketplace di BigCommerce, che permette, con velocit\u00e0 e in maniera intuitiva, di creare scontistiche dedicate ad una o pi\u00f9 categorie e\/o prodotti, di trasformare e modificare in blocco le caratteristiche di categorie e di perfezionare lo smistamento dei prodotti. Tra le esigenze aziendali di Lea &amp; Fl\u00f2, infatti, oltre alla scalabilit\u00e0, c&#8217;era quella di poter gestire al meglio le promozioni e modificare in blocco categorie e prodotti di grandi dimensioni, per evitare che queste operazioni creassero rallentamenti nel lavoro degli e-commerce specialist. \u201cProducts Management\u201d permette di effettuare tante altre operazioni di gestione prodotti, brand e categorie e, grazie al lavoro dei developer di AEFFE Lab, \u00e8 pronta per essere utilizzata per lo sviluppo dei siti e-commerce progettati con BigCommerce in tutto il mondo.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae6db3 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"6ae6db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8c8775 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"c8c8775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/partners.bigcommerce.com\/directory\/partner\/1749185\/aeffe-lab-s-r-l\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">APPROFONDISCI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47c1d3ab e-con-full e-flex e-con e-parent\" data-id=\"47c1d3ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-423d12c elementor-widget elementor-widget-image\" data-id=\"423d12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/leaeflo-portfolio-aeffelab-app-sconti-products-management.png\" class=\"attachment-full size-full wp-image-17861\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca9fdb2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-video\" data-id=\"ca9fdb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-gimos-campagne-mobile-white.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-466bd8a9 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"466bd8a9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61b4cb31 elementor-widget elementor-widget-heading\" data-id=\"61b4cb31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ottimizzazione seo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55e4770a elementor-widget elementor-widget-spacer\" data-id=\"55e4770a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e4349a8 elementor-widget elementor-widget-text-editor\" data-id=\"4e4349a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per migliorare la reperibilit\u00e0 SEO del brand Gimo\u2019s, Aeffe Lab ha studiato il mercato online della giubbotteria e i percorsi di navigazione e di ricerca del prodotto da parte del target. Da uno studio preliminare sul <\/span><b>posizionamento del brand rispetto alle principali keywords di riferimento e ai principali concorrenti online<\/b><span style=\"font-weight: 400;\">, \u00e8 stata sviluppata una strategia SEO, atta a migliorare la presenza del sito sui motori di ricerca e ad implementare una migliore esperienza web per l\u2019utente.\u00a0<br \/><br \/><\/span><span style=\"font-weight: 400;\">Il traffico organico viene stimolato attraverso l\u2019ottimizzazione delle immagini, lo studio dei link, la classificazione delle categorie. Una curata content creation, che evidenzia le caratteristiche e i punti di forza del prodotto attraverso descrizioni dettagliate, costantemente aggiornate, rafforza la strategia e l\u2019ottimizzazione tecnica. Il Seo \u00e8 un lavoro in continua evoluzione: viene monitorato l\u2019andamento delle parole chiave e le tendenze di mercato, per assicurare un\u2019ottimizzazione costante. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-995f91a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"995f91a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-986619d elementor-widget elementor-widget-heading\" data-id=\"986619d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">100% responsive<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74898ae elementor-widget elementor-widget-spacer\" data-id=\"74898ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9f824 elementor-widget elementor-widget-image\" data-id=\"8f9f824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/gimos-responsive-devices.png\" class=\"attachment-full size-full wp-image-13934\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c96e04 e-flex e-con-boxed e-con e-parent\" data-id=\"8c96e04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e62eb7f elementor-widget elementor-widget-heading\" data-id=\"e62eb7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">potrebbe interessarti<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5f8998 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f5f8998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5807c elementor-arrows-position-outside elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"dc5807c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:14508,&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-loop-nothing-found-message\">\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71e135f elementor-widget elementor-widget-spacer\" data-id=\"71e135f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad869a btn-articles-next-prev elementor-widget elementor-widget-post-navigation\" data-id=\"1ad869a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navigazione dell&#039;articolo\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.aeffelab.com\/it\/portfolio_page\/gimos\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i><span class=\"elementor-screen-only\">Precedente<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\"><\/span><span class=\"post-navigation__prev--title\">Gimo&#8217;s<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.aeffelab.com\/it\/portfolio_page\/filippodelaurentiis\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\"><\/span><span class=\"post-navigation__next--title\">Filippo De Laurentiis<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><span class=\"elementor-screen-only\">Successivo<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>B2C Replatforming visita il sito Facebook-f Instagram Lea &#038; Fl\u00f2 Lea &amp; Fl\u00f2: punto di riferimento nella moda in fatto di eccellenza, entusiasmo e cortesia. La storia dell&#8217;azienda inizia nel 1989 quando i fratelli Alessandro e Remo Innocenti e le loro rispettive mogli Lea e Floriana aprono a Pescara il primo negozio di abbigliamento. Nel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17887,"menu_order":0,"template":"","format":"standard","categoria":[57],"class_list":["post-17833","portfolio_page","type-portfolio_page","status-publish","format-standard","has-post-thumbnail","hentry","categoria-e-commerce-b2c"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lea &amp; Fl\u00f2 - Portfolio | Digital Agency &amp; E-commerce consulting | AEFFE Lab<\/title>\n<meta name=\"description\" content=\"AEFFE Lab ha sviluppato un e-commerce su misura, risolto problemi legati alla scalabilit\u00e0 e progettato un\u2019app dedicata per BigCommerce.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lea &amp; Fl\u00f2 - Digital Agency &amp; E-commerce consulting | AEFFE Lab\" \/>\n<meta property=\"og:description\" content=\"AEFFE Lab ha sviluppato un sito su misura, risolto problemi legati alla scalabilit\u00e0 e aver sviluppato un\u2019app dedicata per la scontistica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Agency &amp; E-commerce consulting | AEFFE Lab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aeffelab\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-26T10:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Lea &amp; Fl\u00f2 - Digital Agency &amp; E-commerce consulting | AEFFE Lab\" \/>\n<meta name=\"twitter:description\" content=\"AEFFE Lab ha sviluppato un sito su misura, risolto problemi legati alla scalabilit\u00e0 e aver sviluppato un\u2019app dedicata per la scontistica.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/\",\"url\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/\",\"name\":\"Lea & Fl\u00f2 - Portfolio | Digital Agency &amp; E-commerce consulting | AEFFE Lab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aeffelab.com\\\/wp-content\\\/uploads\\\/aeffelab-portfolio-leaeflo-project-cover.jpg\",\"datePublished\":\"2024-02-21T11:23:54+00:00\",\"dateModified\":\"2024-02-26T10:07:37+00:00\",\"description\":\"AEFFE Lab ha sviluppato un e-commerce su misura, risolto problemi legati alla scalabilit\u00e0 e progettato un\u2019app dedicata per BigCommerce.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aeffelab.com\\\/wp-content\\\/uploads\\\/aeffelab-portfolio-leaeflo-project-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aeffelab.com\\\/wp-content\\\/uploads\\\/aeffelab-portfolio-leaeflo-project-cover.jpg\",\"width\":640,\"height\":640,\"caption\":\"Lea & Fl\u00f2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/portfolio_page\\\/leaeflo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/post%20portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lea &#038; Fl\u00f2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/\",\"name\":\"Digital Agency & E-commerce consulting | AEFFE Lab\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#organization\",\"name\":\"AEFFE Lab Srl\",\"url\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aeffelab.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.aeffelab.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo.svg\",\"width\":841,\"height\":315,\"caption\":\"AEFFE Lab Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aeffelab.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aeffelab\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/aeffe-lab\",\"https:\\\/\\\/www.instagram.com\\\/aeffelab_official\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lea & Fl\u00f2 - Portfolio | Digital Agency &amp; E-commerce consulting | AEFFE Lab","description":"AEFFE Lab ha sviluppato un e-commerce su misura, risolto problemi legati alla scalabilit\u00e0 e progettato un\u2019app dedicata per BigCommerce.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/","og_locale":"it_IT","og_type":"article","og_title":"Lea & Fl\u00f2 - Digital Agency & E-commerce consulting | AEFFE Lab","og_description":"AEFFE Lab ha sviluppato un sito su misura, risolto problemi legati alla scalabilit\u00e0 e aver sviluppato un\u2019app dedicata per la scontistica.","og_url":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/","og_site_name":"Digital Agency &amp; E-commerce consulting | AEFFE Lab","article_publisher":"https:\/\/www.facebook.com\/aeffelab\/","article_modified_time":"2024-02-26T10:07:37+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Lea & Fl\u00f2 - Digital Agency & E-commerce consulting | AEFFE Lab","twitter_description":"AEFFE Lab ha sviluppato un sito su misura, risolto problemi legati alla scalabilit\u00e0 e aver sviluppato un\u2019app dedicata per la scontistica.","twitter_image":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg","twitter_misc":{"Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/","url":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/","name":"Lea & Fl\u00f2 - Portfolio | Digital Agency &amp; E-commerce consulting | AEFFE Lab","isPartOf":{"@id":"https:\/\/www.aeffelab.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/#primaryimage"},"image":{"@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg","datePublished":"2024-02-21T11:23:54+00:00","dateModified":"2024-02-26T10:07:37+00:00","description":"AEFFE Lab ha sviluppato un e-commerce su misura, risolto problemi legati alla scalabilit\u00e0 e progettato un\u2019app dedicata per BigCommerce.","breadcrumb":{"@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/#primaryimage","url":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg","contentUrl":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/aeffelab-portfolio-leaeflo-project-cover.jpg","width":640,"height":640,"caption":"Lea & Fl\u00f2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aeffelab.com\/it\/portfolio_page\/leaeflo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aeffelab.com\/it\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.aeffelab.com\/it\/post%20portfolio\/"},{"@type":"ListItem","position":3,"name":"Lea &#038; Fl\u00f2"}]},{"@type":"WebSite","@id":"https:\/\/www.aeffelab.com\/it\/#website","url":"https:\/\/www.aeffelab.com\/it\/","name":"Digital Agency & E-commerce consulting | AEFFE Lab","description":"","publisher":{"@id":"https:\/\/www.aeffelab.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aeffelab.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aeffelab.com\/it\/#organization","name":"AEFFE Lab Srl","url":"https:\/\/www.aeffelab.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aeffelab.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/2023\/07\/logo.svg","contentUrl":"https:\/\/www.aeffelab.com\/wp-content\/uploads\/2023\/07\/logo.svg","width":841,"height":315,"caption":"AEFFE Lab Srl"},"image":{"@id":"https:\/\/www.aeffelab.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aeffelab\/","https:\/\/it.linkedin.com\/company\/aeffe-lab","https:\/\/www.instagram.com\/aeffelab_official"]}]}},"_links":{"self":[{"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/portfolio_page\/17833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/portfolio_page"}],"about":[{"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/types\/portfolio_page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":168,"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/portfolio_page\/17833\/revisions"}],"predecessor-version":[{"id":18062,"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/portfolio_page\/17833\/revisions\/18062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/media\/17887"}],"wp:attachment":[{"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/media?parent=17833"}],"wp:term":[{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/www.aeffelab.com\/it\/wp-json\/wp\/v2\/categoria?post=17833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}